{"id":4,"count":11,"description":"","link":"https:\/\/www.xgrid.co\/resources\/success-story-category\/devops\/","name":"DevOps","slug":"devops","taxonomy":"success-story-category","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DevOps Archives - Xgrid.co<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.xgrid.co\/resources\/success-story-category\/devops\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DevOps Archives - Xgrid.co\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.xgrid.co\/resources\/success-story-category\/devops\/\" \/>\n<meta property=\"og:site_name\" content=\"Xgrid.co\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.xgrid.co\\\/resources\\\/success-story-category\\\/devops\\\/\",\"url\":\"https:\\\/\\\/www.xgrid.co\\\/resources\\\/success-story-category\\\/devops\\\/\",\"name\":\"DevOps Archives - Xgrid.co\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.xgrid.co\\\/resources\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.xgrid.co\\\/resources\\\/success-story-category\\\/devops\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.xgrid.co\\\/resources\\\/success-story-category\\\/devops\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.xgrid.co\\\/resources\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DevOps\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.xgrid.co\\\/resources\\\/#website\",\"url\":\"https:\\\/\\\/www.xgrid.co\\\/resources\\\/\",\"name\":\"Xgrid.co\",\"description\":\"Learn, Design, Develop, and Engage with Xgrid\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.xgrid.co\\\/resources\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DevOps Archives - Xgrid.co","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.xgrid.co\/resources\/success-story-category\/devops\/","og_locale":"en_US","og_type":"article","og_title":"DevOps Archives - Xgrid.co","og_url":"https:\/\/www.xgrid.co\/resources\/success-story-category\/devops\/","og_site_name":"Xgrid.co","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.xgrid.co\/resources\/success-story-category\/devops\/","url":"https:\/\/www.xgrid.co\/resources\/success-story-category\/devops\/","name":"DevOps Archives - Xgrid.co","isPartOf":{"@id":"https:\/\/www.xgrid.co\/resources\/#website"},"breadcrumb":{"@id":"https:\/\/www.xgrid.co\/resources\/success-story-category\/devops\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.xgrid.co\/resources\/success-story-category\/devops\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.xgrid.co\/resources\/"},{"@type":"ListItem","position":2,"name":"DevOps"}]},{"@type":"WebSite","@id":"https:\/\/www.xgrid.co\/resources\/#website","url":"https:\/\/www.xgrid.co\/resources\/","name":"Xgrid.co","description":"Learn, Design, Develop, and Engage with Xgrid","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.xgrid.co\/resources\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.xgrid.co\/resources\/wp-json\/wp\/v2\/success-story-category\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.xgrid.co\/resources\/wp-json\/wp\/v2\/success-story-category"}],"about":[{"href":"https:\/\/www.xgrid.co\/resources\/wp-json\/wp\/v2\/taxonomies\/success-story-category"}],"wp:post_type":[{"href":"https:\/\/www.xgrid.co\/resources\/wp-json\/wp\/v2\/success-stories?success-story-category=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}